{"id":5195,"date":"2026-03-30T10:59:02","date_gmt":"2026-03-30T14:59:02","guid":{"rendered":"https:\/\/chuv.umontreal.ca\/english\/?post_type=dt_team&#038;p=5195"},"modified":"2026-03-30T10:59:02","modified_gmt":"2026-03-30T14:59:02","slug":"chanie-sorel","status":"publish","type":"dt_team","link":"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/","title":{"rendered":"Chanie Sorel"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Clerk<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Clerk<\/p>\n","protected":false},"featured_media":981,"comment_status":"closed","ping_status":"closed","template":"","dt_team_category":[32],"class_list":["post-5195","dt_team","type-dt_team","status-publish","has-post-thumbnail","hentry","dt_team_category-pharmacie","dt_team_category-32","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chanie Sorel - Internet English<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chanie Sorel - Internet English\" \/>\n<meta property=\"og:description\" content=\"Clerk\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/\" \/>\n<meta property=\"og:site_name\" content=\"Internet English\" \/>\n<meta property=\"og:image\" content=\"http:\/\/chuv.umontreal.ca\/english\/wp-content\/uploads\/sites\/2\/2015\/12\/silhouette-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"284\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/dt_team\\\/chanie-sorel\\\/\",\"url\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/dt_team\\\/chanie-sorel\\\/\",\"name\":\"Chanie Sorel - Internet English\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/dt_team\\\/chanie-sorel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/dt_team\\\/chanie-sorel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/12\\\/silhouette-1.png\",\"datePublished\":\"2026-03-30T14:59:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/dt_team\\\/chanie-sorel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/dt_team\\\/chanie-sorel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/dt_team\\\/chanie-sorel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/12\\\/silhouette-1.png\",\"contentUrl\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/12\\\/silhouette-1.png\",\"width\":300,\"height\":284},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/dt_team\\\/chanie-sorel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Team\",\"item\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/dt_team\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chanie Sorel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/#website\",\"url\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/\",\"name\":\"Internet English\",\"description\":\"Un site utilisant CHUV sites\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chuv.umontreal.ca\\\/english\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chanie Sorel - Internet English","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/","og_locale":"en_US","og_type":"article","og_title":"Chanie Sorel - Internet English","og_description":"Clerk","og_url":"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/","og_site_name":"Internet English","og_image":[{"width":300,"height":284,"url":"http:\/\/chuv.umontreal.ca\/english\/wp-content\/uploads\/sites\/2\/2015\/12\/silhouette-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/","url":"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/","name":"Chanie Sorel - Internet English","isPartOf":{"@id":"https:\/\/chuv.umontreal.ca\/english\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/#primaryimage"},"image":{"@id":"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/#primaryimage"},"thumbnailUrl":"https:\/\/chuv.umontreal.ca\/english\/wp-content\/uploads\/sites\/2\/2015\/12\/silhouette-1.png","datePublished":"2026-03-30T14:59:02+00:00","breadcrumb":{"@id":"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/#primaryimage","url":"https:\/\/chuv.umontreal.ca\/english\/wp-content\/uploads\/sites\/2\/2015\/12\/silhouette-1.png","contentUrl":"https:\/\/chuv.umontreal.ca\/english\/wp-content\/uploads\/sites\/2\/2015\/12\/silhouette-1.png","width":300,"height":284},{"@type":"BreadcrumbList","@id":"https:\/\/chuv.umontreal.ca\/english\/dt_team\/chanie-sorel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/chuv.umontreal.ca\/english\/"},{"@type":"ListItem","position":2,"name":"Team","item":"https:\/\/chuv.umontreal.ca\/english\/dt_team\/"},{"@type":"ListItem","position":3,"name":"Chanie Sorel"}]},{"@type":"WebSite","@id":"https:\/\/chuv.umontreal.ca\/english\/#website","url":"https:\/\/chuv.umontreal.ca\/english\/","name":"Internet English","description":"Un site utilisant CHUV sites","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chuv.umontreal.ca\/english\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/chuv.umontreal.ca\/english\/wp-json\/wp\/v2\/dt_team\/5195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chuv.umontreal.ca\/english\/wp-json\/wp\/v2\/dt_team"}],"about":[{"href":"https:\/\/chuv.umontreal.ca\/english\/wp-json\/wp\/v2\/types\/dt_team"}],"replies":[{"embeddable":true,"href":"https:\/\/chuv.umontreal.ca\/english\/wp-json\/wp\/v2\/comments?post=5195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chuv.umontreal.ca\/english\/wp-json\/wp\/v2\/media\/981"}],"wp:attachment":[{"href":"https:\/\/chuv.umontreal.ca\/english\/wp-json\/wp\/v2\/media?parent=5195"}],"wp:term":[{"taxonomy":"dt_team_category","embeddable":true,"href":"https:\/\/chuv.umontreal.ca\/english\/wp-json\/wp\/v2\/dt_team_category?post=5195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}