{"id":2160,"date":"2020-12-05T16:13:13","date_gmt":"2020-12-05T21:13:13","guid":{"rendered":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/?p=2160"},"modified":"2021-02-24T08:59:51","modified_gmt":"2021-02-24T13:59:51","slug":"soap-journalier","status":"publish","type":"post","link":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/soap-journalier\/","title":{"rendered":"SOAP journalier (05-12-2020)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">N. B.  Avant d\u00e9buter l&rsquo;entrer des SOAP dans le dossier patient pour la premi\u00e8re fois, veuillez valider avec votre service leur fonctionnement et r\u00e8gles pour les entr\u00e9es SOAP,  car il y a plusieurs options possibles.  Cette le\u00e7on pr\u00e9sente les deux fa\u00e7ons les plus communes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour pouvoir faire un SOAP, vous devez entr\u00e9e au moins 1 probl\u00e8me actif dans la visite.  Voir <a href=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/?p=2149\">cette le\u00e7on<\/a> pour plus d&rsquo;information sur les ajouts de probl\u00e8mes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vous avez 5 jours pour commencer un SOAP dans le syst\u00e8me.  Par exemple, vous avez jusqu&rsquo;au 5 janvier pour faire votre SOAP d\u00e9butant le 1 janvier.  Si vous n&rsquo;avez pas commencer en tenant compte de ce d\u00e9lai, la date ne sera plus disponible et vous ne pourrez plus y faire d&rsquo;entr\u00e9e.<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>SOAP par jour<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Sur la ligne avec la date appropri\u00e9e, cliquer sur :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>S pour ajouter la boite Subjectif<\/li><li>O pour ajouter la boite Objectif<\/li><li>A pour ajouter la boite \u00abAssessment\u00bb (\u00e9valuation)<\/li><li>P pour ajouter la boite Plan<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"102\" src=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJour-700x102.png\" alt=\"\" class=\"wp-image-2175\" srcset=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJour-700x102.png 700w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJour-300x44.png 300w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJour-768x112.png 768w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJour-1536x224.png 1536w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJour.png 2014w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la boite qui est ajout\u00e9e (que ce soit S, O, A ou P), vous pouvez \u00e9galement faire les actions suivantes:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"301\" src=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJourOptions-700x301.png\" alt=\"\" class=\"wp-image-2177\" srcset=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJourOptions-700x301.png 700w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJourOptions-300x129.png 300w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJourOptions-768x330.png 768w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJourOptions-1536x660.png 1536w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparJourOptions.png 1922w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li>a &#8211; Mettre la boite en plein \u00e9cran<\/li><li>b &#8211; Sauvegarder le texte et quitter le mode d&rsquo;\u00e9dition<\/li><li>c &#8211; Cliquer pour acc\u00e9der \u00e0 d&rsquo;autres entr\u00e9es dans le dossier m\u00e9dical et les ajouter dans la boite.  Par exemple, vous pouvez prendre le texte d&rsquo;un rapport d&rsquo;imagerie et l&rsquo;ins\u00e9rer dans le SOAP.  Vous pouvez modifier le texte une fois dans la boite.<\/li><li>d- Les v\u00e9t\u00e9rinaires responsables de v\u00e9rifier les SOAPs peuvent utiliser ce bouton pour v\u00e9rifier le SOAP.  <\/li><li>e &#8211; Les v\u00e9t\u00e9rinaires responsables de la v\u00e9rification des SOAPs peuvent \u00e9galement les annuler (rej\u00e9ter).<\/li><li>f &#8211; Cliquer sur ce bouton pour changer le statut vers en \u00abattente de r\u00e9vision\u00bb pour indiquer que votre SOAP est pr\u00eat pour a \u00eatre r\u00e9vis\u00e9 par le v\u00e9t\u00e9rinaire.  Cette option ne fait que changer le statut.<\/li><li>g &#8211; Cliquer sur ce bouton pour changer le statut vers \u00aben attente de r\u00e9vision\u00bb pour indiquer que votre SOAP est pr\u00eat pour les r\u00e9visions du v\u00e9t\u00e9rinaire et \u00e9galement envoyer un message au v\u00e9t\u00e9rinaire traitant via les \u00abNotifications\u00bb.<\/li><li>h &#8211; Cette option est le moyen pour le v\u00e9t\u00e9rinaire d&rsquo;ajouter des notes pour vous.  Ces commentaires sont uniquement pour l&rsquo;enseignement et ne font pas partie du SOAP officiel.  L&rsquo;utilisation de commentaires est selon le fonctionnement sp\u00e9cifique des V\u00e9t\u00e9rinaires.    <\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>SOAP par probl\u00e8me<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ouvrir les d\u00e9tails de la date appropri\u00e9e (cliquer sur le triangle \u00e0 gauche de la date dans la section SOAP) pour voir l&rsquo;ensemble des probl\u00e8mes actifs pour la journ\u00e9e et acc\u00e9der aux options.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"113\" src=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProbleme-700x113.png\" alt=\"\" class=\"wp-image-2184\" srcset=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProbleme-700x113.png 700w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProbleme-300x48.png 300w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProbleme-768x124.png 768w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProbleme-1536x247.png 1536w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProbleme.png 1940w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li>a &#8211; Sur la ligne avec la date appropri\u00e9, cliquer sur: <ul><li>S pour ajouter la boite Subjectif<\/li><li>O pour ajouter la boite Objectif<\/li><li>A pour ajouter la boite \u00abAssessment\u00bb (\u00e9valuation)<\/li><li>P pour ajouter la boite Plan<\/li><\/ul><\/li><li>b &#8211; Si le probl\u00e8me est un doublon, les v\u00e9t\u00e9rinaires et TSAs ont la possibilit\u00e9 de faire une fusion avec un autre probl\u00e8me.  Cliquer sur ce bouton pour faire une fusion.<\/li><li>c &#8211; Cliquer sur ce bouton pour changer le nom du probl\u00e8me.<\/li><li>d &#8211; Cliquer sur ce bouton pour indiquer que  le probl\u00e8me est inactif pour la visite.  Il ne sera plus visible dans la journ\u00e9e o\u00f9 la suite de la visite.  Uniquement les v\u00e9t\u00e9rinaires et TSAs doivent faire cette \u00e9tape.  Si cette \u00e9tape a \u00e9t\u00e9 faite faite par erreur, vous devrez rajouter le probl\u00e8me dans la visite.<\/li><li>e &#8211; Cliquer sur ce bouton pour indiquer que le probl\u00e8me est maintenant r\u00e9solu<\/li><li>f &#8211; Ne pas cliquer sur ce bouton.  Il devrait changer le statut vers effac\u00e9, mais il en fait, il brise l&rsquo;interactivit\u00e9 entre le SOAP et la liste des probl\u00e8mes dans la version de Vetview  2.0.12+.  <\/li><li>g &#8211; Cliquer sur ce bouton pour voir la date ou le probl\u00e8me a \u00e9t\u00e9 ajout\u00e9 dans le dossier du patient.  Si s&rsquo;agit une r\u00e9\u00e9valuation, la date sera li\u00e9e avec une visite ant\u00e9rieure.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s qu&rsquo;au moins une boite est \u00e9t\u00e9 ajout\u00e9e (que ce soit S, O, A ou P), vous pourrez \u00e9galement faire les actions suivantes sur la ligne du probl\u00e8me et pour l&rsquo;ensemble des boites associ\u00e9es avec le probl\u00e8me s\u00e9lectionn\u00e9:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"380\" src=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProblemOptions-700x380.png\" alt=\"\" class=\"wp-image-2187\" srcset=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProblemOptions-700x380.png 700w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProblemOptions-300x163.png 300w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProblemOptions-768x417.png 768w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProblemOptions-1536x835.png 1536w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPparProblemOptions.png 1906w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li>a &#8211; Mettre la boite en plein \u00e9cran<\/li><li>b &#8211; Les v\u00e9t\u00e9rinaires responsables de la v\u00e9rification des SOAPs peuvent pousser ce bouton pour v\u00e9rifier le SOAP.<\/li><li>c &#8211; Les v\u00e9t\u00e9rinaires responsables de la v\u00e9rification des SOAPs peuvent \u00e9galement les annuler (rej\u00e9ter)<\/li><li>d &#8211; Cliquer sur ce bouton pour changer le statut vers en \u00abattente de r\u00e9vision pour indiquer que votre SOAP est pr\u00eat pour les r\u00e9visions du v\u00e9t\u00e9rinaire. Cette option ne fait que changer le statut.<\/li><li>e &#8211; Cliquer sur ce bouton pour changer le statut vers \u00aben attente de r\u00e9vision\u00bb pour indiquer que votre SOAP est pr\u00eat pour les r\u00e9visions du v\u00e9t\u00e9rinaire et aussi envoyer un message au v\u00e9t\u00e9rinaire traitant via les \u00abNotifications\u00bb.<\/li><li>f &#8211; Ajouter une autre lettre du S, O, A ou P (vous pouvez avoir une boite par lettre et par probl\u00e8me)<\/li><li>g &#8211; Cette option est le moyen par lequel le v\u00e9t\u00e9rinaire peut ajouter des notes pour vous. Ces commentaires sont uniquement pour l&rsquo;enseignement et ne font pas partie du SOAP officiel. L&rsquo;utilisation des commentaires est selon le fonctionnement sp\u00e9cifique des V\u00e9t\u00e9rinaires.<\/li><li>h &#8211; Si le probl\u00e8me est un doublon, les v\u00e9t\u00e9rinaires et TSAs peuvent faire une fusion avec un autre probl\u00e8me. Cliquer sur ce bouton faire une fusion.<\/li><li>i &#8211; Cliquer sur ce bouton pour changer le nom du probl\u00e8me.<\/li><li>j &#8211; Cliquer sur ce bouton pour indiquer que le probl\u00e8me est inactif pour la visite. Il ne sera plus visible dans la journ\u00e9e ni la suite de la visite. Uniquement les v\u00e9t\u00e9rinaires et TSAs doivent faire cette \u00e9tape. Si cette \u00e9tape est faite par erreur, vous devrez rajouter le probl\u00e8me dans la visite.<\/li><li>k &#8211; Cliquer sur ce bouton pour indiquer que le probl\u00e8me est maintenant r\u00e9solu.<\/li><li>l &#8211; Ne pas cliquer ce bouton. Il devrait changer le statut vers effac\u00e9, mais il brise en fait l&rsquo;interactivit\u00e9 entre le SOAP et la liste des probl\u00e8mes dans la version de VetView 2.0.12+.<\/li><li>m &#8211; Cliquer sur ce bouton pour voir la date o\u00f9 le probl\u00e8me a \u00e9t\u00e9 ajout\u00e9 dans le dossier du patient. Si s&rsquo;agit d&rsquo;une r\u00e9\u00e9valuation, la date sera li\u00e9e avec une visite ant\u00e9rieure.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la boite qui est ajout\u00e9e (que ce soit S, O, A ou P), vous pouvez \u00e9galement faire les actions suivantes:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"306\" src=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPbox-700x306.png\" alt=\"\" class=\"wp-image-2189\" srcset=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPbox-700x306.png 700w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPbox-300x131.png 300w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPbox-768x336.png 768w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPbox-1536x672.png 1536w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/12\/SOAPbox.png 1782w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li>a &#8211; Sauvegarder le texte et quitterle mode d&rsquo;\u00e9dition<\/li><li>b &#8211; Cliquer pour acc\u00e9der \u00e0 d&rsquo;autres entr\u00e9es dans le dossier m\u00e9dical et les ajouter dans la boite. Par exemple, vous pouvez prendre le texte d&rsquo;un rapport d&rsquo;imagerie et l&rsquo;ins\u00e9rer dans le SOAP. Vous pouvez modifier le texte une fois dans la boite.<\/li><li>c &#8211; Les v\u00e9t\u00e9rinaires responsables de v\u00e9rifier les SOAPs peuvent pousser ce bouton pour v\u00e9rifier le SOAP.<\/li><li>d &#8211; Les v\u00e9t\u00e9rinaires responsables de la v\u00e9rification des SOAPs peuvent \u00e9galement les annuler (rej\u00e9ter)<\/li><li>e &#8211; Cliquer sur ce bouton pour changer le statut vers \u00aben attente de r\u00e9vision\u00bb pour indiquer que votre SOAP est pr\u00eat pour les r\u00e9visions du v\u00e9t\u00e9rinaire. Cette option ne fait que changer le statut.<\/li><li>f &#8211; Cliquer sur ce bouton pour changer le statut vers \u00aben attente de r\u00e9vision\u00bb pour indiquer que votre SOAP est pr\u00eat pour les r\u00e9visions du v\u00e9t\u00e9rinaire et aussi envoyer un message au v\u00e9t\u00e9rinaire traitant via les \u00abNotifications\u00bb.<\/li><li>g &#8211; Cette option est le moyen par lequel le v\u00e9t\u00e9rinaire peut ajouter des notes pour vous. Ces commentaires sont uniquement pour l&rsquo;enseignement et ne font pas partie du SOAP officiel. L&rsquo;utilisation des commentaires est selon le fonctionnement sp\u00e9cifiques des V\u00e9t\u00e9rinaires.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>SOAP par date et probl\u00e8me<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez \u00e9galement utilis\u00e9 un m\u00e9lange des deux types de SOAP.  \u00c0 titre d&rsquo;exemple, vous pouvez mettre le \u00abS\u00bb g\u00e9n\u00e9rique sur la date et faire les O, A et P au niveau des probl\u00e8mes.  <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(<em>derni\u00e8re maj 16 d\u00e9c. 2020<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N. B. Avant d\u00e9buter l&rsquo;entrer des SOAP dans le dossier patient pour la premi\u00e8re fois, veuillez valider avec votre service leur fonctionnement et r\u00e8gles pour les entr\u00e9es SOAP, car il y a plusieurs options possibles. Cette le\u00e7on pr\u00e9sente les deux fa\u00e7ons les plus communes. Pour pouvoir faire un SOAP, vous devez entr\u00e9e au moins 1 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44,56,24,90,7,4,6],"tags":[],"class_list":["post-2160","post","type-post","status-publish","format-standard","hentry","category-dossier-medical-dmv","category-dossier-medical-stagiaire-etudiant","category-dossier-medical-tsa","category-index","category-stagiaires-etudiants","category-tsa-tim","category-veterinaire-resident-interne"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 12:19:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/posts\/2160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/comments?post=2160"}],"version-history":[{"count":14,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/posts\/2160\/revisions"}],"predecessor-version":[{"id":3222,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/posts\/2160\/revisions\/3222"}],"wp:attachment":[{"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/media?parent=2160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/categories?post=2160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/tags?post=2160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}