{"id":441,"date":"2020-11-12T14:12:11","date_gmt":"2020-11-12T19:12:11","guid":{"rendered":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/?p=441"},"modified":"2021-02-24T09:22:24","modified_gmt":"2021-02-24T14:22:24","slug":"gestion-horaires-rendre-un-actif-visible","status":"publish","type":"post","link":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/gestion-horaires-rendre-un-actif-visible\/","title":{"rendered":"Gestion horaires: rendre un horaire actif\/visible (12-11-2020)"},"content":{"rendered":"\n<p>En tant que gestionnaire des horaires, vous avez le pouvoir de rendre des horaires disponibles ou non pour des p\u00e9riodes\/jours pr\u00e9cis.<\/p>\n\n\n\n<p>Les horaires sont non-visibles: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Lors de la cr\u00e9ation d&#8217;un nouvel horaire<\/li><li>Lors d&#8217;une prolongation d&#8217;un horaire existant (voir la section \u00c0 noter dans <a href=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/gestion-horaires-explications-de-base\/\">cette le\u00e7on<\/a>)<\/li><li>Si un gestionnaire des horaires l&#8217;a cach\u00e9 au complet, ou pour une p\u00e9riode sp\u00e9cifique<\/li><\/ul>\n\n\n\n<p>Selon le chemin pris, vous pouvez noter qu&#8217;un horaire est non-visible:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Le choix d&#8217;horaire n&#8217;est pas disponible dans la colonne de gauche sur l&#8217;\u00e9cran d&#8217;horaire<ul><li>NB:  Si vous utilisez l&#8217;option Montrer uniquement mes horaires cela peut \u00e9galement cacher des choix d&#8217;horaire.  Si vous utilisez cette option, il faut la d\u00e9s\u00e9lectionner pour valider si cela est la source d&#8217;un l&#8217;horaire cach\u00e9.<\/li><\/ul><\/li><li>La colonne est visible au milieu, mais les actions sont bloqu\u00e9s, et indique un statut de cach\u00e9 avec la colonne en gris p\u00e2le.<\/li><\/ul>\n\n\n\n<p><strong>Pour rendre l&#8217;horaire disponible:<\/strong><\/p>\n\n\n\n<p>* N.B. l&#8217;horaire doit exister et doit \u00eatre prolong\u00e9 pour inclure le(s) date(s) d\u00e9sir\u00e9es pour \u00eatre disponible pour pouvoir suivre ces instructions.  Voir la section \u00c0 noter dans <a href=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/gestion-horaires-explications-de-base\/\">cette le\u00e7on<\/a>.<\/p>\n\n\n\n<p>1 &#8211; faire un clique de droit sur la section \u00e0 gauche \u00abCacher\/Montrer liste horaires\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.03-PM.png\" alt=\"\" class=\"wp-image-461\" width=\"229\" height=\"329\" srcset=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.03-PM.png 462w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.03-PM-209x300.png 209w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/figure>\n\n\n\n<p>2 &#8211; choisir l&#8217;option \u00abRendre un horaire disponible\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.53-PM-700x341.png\" alt=\"\" class=\"wp-image-462\" width=\"441\" height=\"215\" srcset=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.53-PM-700x341.png 700w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.53-PM-300x146.png 300w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.53-PM-768x375.png 768w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.53-PM-800x390.png 800w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.53-PM.png 1316w\" sizes=\"auto, (max-width: 441px) 100vw, 441px\" \/><\/figure>\n\n\n\n<p>3 &#8211; dans la fen\u00eatre qui s&#8217;ouvre, <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/07b-horaire-setup-show-hide-schedule.png\" alt=\"\" class=\"wp-image-467\" width=\"402\" height=\"220\" srcset=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/07b-horaire-setup-show-hide-schedule.png 646w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/07b-horaire-setup-show-hide-schedule-300x164.png 300w\" sizes=\"auto, (max-width: 402px) 100vw, 402px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li>choisir l&#8217;horaire (l&#8217;horaire \u00e9tant la \u00abcolonne\u00bb dans ce cas)<ul><li>Les noms visibles sont uniquement les noms visibles en haut d&#8217;une colonne.  Cela n&#8217;inclus donc pas, ni le nom du service ni le nom du groupe.<\/li><\/ul><\/li><li>choisir la p\u00e9riode pour laquelle l&#8217;horaire doit \u00eatre disponible<ul><li>Si la p\u00e9riode est un jour, mettre la m\u00eame date dans le champ Date d\u00e9but et le champ Date fin.<\/li><\/ul><\/li><li>cliquer sur le bouton \u00abSauvegarder\u00bb<\/li><\/ul>\n\n\n\n<p>4 &#8211; La colonne est maintenant visible.  <\/p>\n\n\n\n<p><strong>Pour rendre l&#8217;horaire non-disponible:<\/strong><\/p>\n\n\n\n<p>1 &#8211; faire un clique de droit sur la section \u00e0 gauche \u00abCacher\/Montrer liste horaires\u00bb (image disponible dans la section \u00abPour rendre l&#8217;horaire visible:\u00bb en haut)<\/p>\n\n\n\n<p>2 &#8211; choisir l&#8217;option \u00abRendre un horaire non-disponible\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.43-PM-700x351.png\" alt=\"\" class=\"wp-image-477\" width=\"428\" height=\"215\" srcset=\"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.43-PM-700x351.png 700w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.43-PM-300x150.png 300w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.43-PM-768x385.png 768w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.43-PM-800x401.png 800w, https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-content\/uploads\/sites\/6\/2020\/11\/Screen-Shot-2020-11-12-at-2.28.43-PM.png 1368w\" sizes=\"auto, (max-width: 428px) 100vw, 428px\" \/><\/figure>\n\n\n\n<p>3 &#8211; Dans la fen\u00eatre qui s&#8217;ouvre, (image disponible dans la section \u00abPour rendre l&#8217;horaire visible:\u00bb en haut)<\/p>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-6526beaf-52f8-4173-8180-dffe7494a41a\"><li>choisir l&#8217;horaire (l&#8217;horaire \u00e9tant la \u00abcolonne\u00bb dans ce cas)<ul><li>Les noms visibles sont uniquement les noms visibles en haut d&#8217;une colonne. Cela n&#8217;inclus donc pas, ni le nom du service ni le nom du groupe.<\/li><\/ul><\/li><li>choisir la p\u00e9riode pour laquelle l&#8217;horaire doit \u00eatre non disponible<ul><li>Si la p\u00e9riode est un jour, mettre la m\u00eame date dans le champ Date d\u00e9but et le champ Date fin.<\/li><\/ul><\/li><li>cliquer sur le bouton \u00abSauvegarder\u00bb<\/li><\/ul>\n\n\n\n<p>4 &#8211; La colonne est maintenant cach\u00e9e pour la p\u00e9riode choisi.<\/p>\n\n\n\n<p>* NB:  S&#8217;il y a des plages et RVs sur la journ\u00e9e, ils seront gard\u00e9s dans le syst\u00e8me, mais ne seront plus visible sur l&#8217;horaire.  Faire attention de ne pas cacher des journ\u00e9es ayant des horaires de pris.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>(MAJ 2020 nov 12)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En tant que gestionnaire des horaires, vous avez le pouvoir de rendre des horaires disponibles ou non pour des p\u00e9riodes\/jours pr\u00e9cis. Les horaires sont non-visibles: Lors de la cr\u00e9ation d&#8217;un nouvel horaire Lors d&#8217;une prolongation d&#8217;un horaire existant (voir la section \u00c0 noter dans cette le\u00e7on) Si un gestionnaire des horaires l&#8217;a cach\u00e9 au complet, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90,86],"tags":[],"class_list":["post-441","post","type-post","status-publish","format-standard","hentry","category-index","category-secretariat-gestion-parametres"],"_links":{"self":[{"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/posts\/441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/comments?post=441"}],"version-history":[{"count":33,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/posts\/441\/revisions"}],"predecessor-version":[{"id":3261,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/posts\/441\/revisions\/3261"}],"wp:attachment":[{"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/media?parent=441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/categories?post=441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chuv.umontreal.ca\/intranet\/ti\/wp-json\/wp\/v2\/tags?post=441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}